{"id":8211,"date":"2014-07-17T19:03:00","date_gmt":"2014-07-17T17:03:00","guid":{"rendered":"http:\/\/www.mused-mosaik.de\/?p=8211"},"modified":"2015-02-15T10:11:00","modified_gmt":"2015-02-15T09:11:00","slug":"la-mia-prima-commissione","status":"publish","type":"post","link":"https:\/\/www.mused-mosaik.de\/it\/la-mia-prima-commissione\/","title":{"rendered":"La mia prima &#8220;commissione&#8221;"},"content":{"rendered":"<p>Prima di iniziare <a title=\"Spilimbergo 24\/7\" href=\"http:\/\/www.mused-mosaik.de\/it\/category\/blog\">la mia formazione presso la Scuola Mosaicisti<\/a> ho lavorato come<em> online manager<\/em> presso una ditta che si occupava di elettromedicali. Il mio ultimo giorno di lavoro (che ricordo come vero RIinizio), la moglie del CEO mi disse sorridendo:<\/p>\n<p>&lt;&lt;Signorina Bastisch, si rende conto che il lavoro finale della sua formazione dovr\u00e0 essere il logo della nostra azienda?&gt;&gt;<\/p>\n<p>Questo accadde quasi un anno fa, ma io la presi sul serio. Non volendo per\u00f2 aspettare fino al terzo anno della formazione (sicura che sarei stata occupata con altri progetti) ho realizzato il mosaico durante il tempo libero a Spilimbergo.<\/p>\n<p>Pochi giorni fa, ho spedito il mio\u00a0 &#8220;mosaico commissionato&#8221; di smalti e marmi alla mia ex sede. E&#8230;<\/p>\n<p>&#8230;A giudicare dalle facce sorridenti dei miei ex-colleghi in foto, penso che la sorpresa sia riuscita!<\/p>\n<div id='gallery-1' class='custom-gallery galleryid-8211'><figure class='gallery-item'><a href='https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo151.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"413\" src=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo151.jpg\" class=\"attachment-big-size no-lazy\" alt=\"\" srcset=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo151.jpg 700w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo151-300x177.jpg 300w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo151-370x218.jpg 370w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo151-570x336.jpg 570w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><figure class='gallery-item'><a href='https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo141.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"428\" src=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo141.jpg\" class=\"attachment-big-size no-lazy\" alt=\"\" srcset=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo141.jpg 700w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo141-300x183.jpg 300w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo141-370x226.jpg 370w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo141-570x349.jpg 570w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><figure class='gallery-item'><a href='https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo131.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"410\" src=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo131.jpg\" class=\"attachment-big-size no-lazy\" alt=\"\" srcset=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo131.jpg 700w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo131-300x176.jpg 300w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo131-370x217.jpg 370w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo131-570x334.jpg 570w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><figure class='gallery-item'><a href='https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo111.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"424\" src=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo111.jpg\" class=\"attachment-big-size no-lazy\" alt=\"\" srcset=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo111.jpg 700w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo111-300x182.jpg 300w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo111-370x224.jpg 370w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo111-570x345.jpg 570w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><figure class='gallery-item'><a href='https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo101.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"425\" src=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo101.jpg\" class=\"attachment-big-size no-lazy\" alt=\"\" srcset=\"https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo101.jpg 700w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo101-300x182.jpg 300w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo101-370x225.jpg 370w, https:\/\/www.mused-mosaik.de\/wp-content\/uploads\/2014\/07\/pfm_medical_logo101-570x346.jpg 570w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Prima di iniziare la mia formazione di mosaico ho lavorato come online manager da una ditta che si occupa di&#8230;<\/p>\n","protected":false},"author":3,"featured_media":8204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[409],"tags":[1325,1219],"class_list":["post-8211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","tag-mosaici-fatti-da-miriam","tag-spilimbergo-it","post-item","post-even"],"_links":{"self":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/posts\/8211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/comments?post=8211"}],"version-history":[{"count":0,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/posts\/8211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/media\/8204"}],"wp:attachment":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/media?parent=8211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/categories?post=8211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/tags?post=8211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}