{"id":13881,"date":"2016-02-26T13:13:12","date_gmt":"2016-02-26T12:13:12","guid":{"rendered":"http:\/\/www.mused-mosaik.de\/?p=13881"},"modified":"2017-07-09T21:38:43","modified_gmt":"2017-07-09T19:38:43","slug":"vincenzo-labellarte-e-i-ritratti-mosaicista","status":"publish","type":"post","link":"https:\/\/www.mused-mosaik.de\/it\/vincenzo-labellarte-e-i-ritratti-mosaicista\/","title":{"rendered":"Vincenzo Labellarte: Ritratti di mosaicisti"},"content":{"rendered":"<p><b><i>Vincenzo, ci siamo incontrati a Spilimbergo quando avevi gi\u00e0 iniziato a fotografare mosaicisti della regione. Come ti \u00e8 venuta quest&#8217;idea?<\/i><\/b><\/p>\n<p>Provenendo da Roma e occupandomi principalmente di paesaggio urbano cercavo un tema che mi aiutasse a conoscere meglio il territorio friulano. Dopo alcuni sopralluoghi e approfondimenti che hanno finito per definire altri progetti sul paesaggio, ho deciso di analizzare anche le attivit\u00e0 che piu&#8217; caratterizzano il territorio e per quanto riguarda Spilimbergo, il mosaico \u00e8 sicuramente tra le pi\u00f9 note: ho quindi scelto di passare da una visione su scala ampia e territoriale ad una molto ravvicinata su soggetti e dettagli.<\/p>\n<p><b><i>Ho gi\u00e0 conosciuto\u00a0q<\/i><\/b><b><i>uasi tutti i mosaicisti che per ora hai fotografato. In ogni foto riconosco la personalit\u00e0 dell&#8217;artista, il modo di lavorare, lo stile del mosaico stesso. Quanto tempo ti prendi per capire chi stai fotografando e cosa \u00e8 particolare nel modo di lavorare dell&#8217;artista?<\/i><\/b><\/p>\n<p>Trattandosi di un progetto a medio termine cerco di prendermi tutto il tempo necessario. Di solito la scelta dei soggetti avviene tramite passaparola, chiedendo a chi ho gi\u00e0 fotografato di suggerirmi altri artisti di loro interesse, cos\u00ec facendo posso gi\u00e0 iniziare a farmi un&#8217;idea delle specificit\u00e0 di questi ultimi. Successivamente, parlando con loro e osservando le loro opere tramite mostre, pubblicazioni o direttamente nei loro atelier, cerco di definire un&#8217;idea su cui lavorare.<\/p>\n<p><b><i>Mi piace molto come un vestito o un particolare del mosaicista riprende qualcosa del dettaglio dell&#8217;opera presentata accanto. Chi sceglie cosa?<\/i><\/b><\/p>\n<p>Anche se mi occupo autonomamente delle scelte finali mi interessa che gli artisti siano coinvolti attivamente nel progetto. Di solito spiego anticipatamente il senso del mio lavoro e lascio che siano loro stessi a proporre un modo per creare un collegamento con l&#8217;opera che ritengono piu&#8217; rappresentativa, in alcuni casi intervengo per rendere questo rapporto piu&#8217; chiaro ed in sintonia con gli altri ritratti, ma uno degli aspetti piu&#8217; interessanti \u00e8 che spesso questo collegamento si realizza spontaneamente, senza troppe indicazioni.<\/p>\n<p><b><i>Con la serie vuoi limitarti a mosaicisti della regione?<\/i><\/b><\/p>\n<p>Al momento per questioni pratiche penso di continuare a lavorare sullo stesso territorio, ma non mi dispiacerebbe ampliare il raggio d&#8217;azione, del resto la maggior parte dei mosaicisti che ho incontrato provengono non solo dal Friuli ma anche da diverse parti d&#8217;Europa e in alcuni casi addirittura da oltre-oceano. Nelle loro opere si viene a creare un incontro tra la loro cultura di provenienza e quella del luogo di formazione, il che col tempo ha trasformato la natura stessa del progetto che \u00e8 passato da un&#8217;indagine su un territorio specifico al racconto del lavoro di una serie di artisti di diversa provenienza accomunati dalla stessa passione.<\/p>\n<p><b><i>Da quando hai iniziato a lavorare sulla serie cosa ti \u00e8 rimasto impresso, cosa ti affascina nel presentare mosaicisti contemporanei?<\/i><\/b><\/p>\n<p>Sicuramente il fatto che in una societ\u00e0 sempre pi\u00f9 dominata da velocit\u00e0 e virtualit\u00e0 ci sia chi invece sceglie di proseguire e far evolvere una tradizione secolare basata sulla lentezza e sulla materia, da cui il titolo del progetto.<\/p>\n<p><em><strong>Complimenti per il tuo lavoro. Siamo curiosi chi ci presenterai in futuro. In tanto buon proseguimento con il progetto\u00a0e buone cose!<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>Nato a Bari nel 1974, Vincenzo Labellarte vive e lavora tra il Friuli e Roma, dopo la laurea in Architettura si interessa allo studio della fotografia come strumento di rappresentazione e analisi della citt\u00e0 e del territorio. Collabora come fotografo con diversi studi di architettura alla realizzazione di progetti multimediali di divulgazione. Nel 2015, in occasione dell&#8217;<em>Open House<\/em> di Roma organizza <em>Niente Da Vedere<\/em>, manifestazione multimediale sulla citt\u00e0. Ha pubblicato su <em>L&#8217;Espresso<\/em> ed ha esposto a Torino e a Roma nel circuito Off di <em>Fotoleggendo 2014<\/em>, e al <em>2NC-Fest multipli cities 2015<\/em>, biennale di fotografia urbana.<\/p>\n<hr \/>\n<p>Per sapere di pi\u00f9 sul progetto visitate anche il sito web di Vincenzo vincenzolabellarte.it.<\/p>\n<p>Finora fotografati per <strong><em>MATERIAE<\/em><\/strong>: Sofia Romoli, Francesco Folla, <a href=\"http:\/\/www.mused-mosaik.de\/it\/2015\/12\/03\/mosaizm\/\">Andrea Besana<\/a>, <a href=\"http:\/\/www.mused-mosaik.de\/it\/2014\/04\/03\/arab-mosaico-3\/\">Laura Carraro<\/a>,\u00a0<a href=\"http:\/\/www.mused-mosaik.de\/it\/2015\/01\/12\/michela-mazzero-3\/\">Michela Mazzero<\/a>,\u00a0Romuald Mesdagh, Luca Nardini,\u00a0<a href=\"http:\/\/www.mused-mosaik.de\/it\/2015\/12\/03\/mosaizm\/\">Matko Kezele<\/a>,\u00a0<a href=\"http:\/\/www.mused-mosaik.de\/it\/2012\/10\/11\/atupertucon-minola\/\">Ruth Minola Scheibler<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da una ricerca sul paesaggio friulano \u00e8 uscito un profondo interesse per i mosaicisti della regione.<\/p>\n","protected":false},"author":3,"featured_media":13912,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[133],"tags":[1195],"class_list":["post-13881","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-gente","tag-spilimbergo-2","post_format-post-format-gallery","post-item","post-even"],"_links":{"self":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/posts\/13881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/comments?post=13881"}],"version-history":[{"count":0,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/posts\/13881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/media\/13912"}],"wp:attachment":[{"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/media?parent=13881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/categories?post=13881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mused-mosaik.de\/it\/wp-json\/wp\/v2\/tags?post=13881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}